{"id":1117,"count":1,"description":"","link":"http:\/\/travelblog.md\/es\/tag\/elena-scobioala\/","name":"Elena Scobioala","slug":"elena-scobioala","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/travelblog.md\/es\/wp-json\/wp\/v2\/tags\/1117"}],"collection":[{"href":"http:\/\/travelblog.md\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/travelblog.md\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/travelblog.md\/es\/wp-json\/wp\/v2\/posts?tags=1117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}